{"id":85640,"date":"2026-05-13T09:42:18","date_gmt":"2026-05-13T12:42:18","guid":{"rendered":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/05\/13\/prefeitura-ja-recolheu-7-toneladas-de-fios\/"},"modified":"2026-05-13T09:42:18","modified_gmt":"2026-05-13T12:42:18","slug":"prefeitura-ja-recolheu-7-toneladas-de-fios","status":"publish","type":"post","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/05\/13\/prefeitura-ja-recolheu-7-toneladas-de-fios\/","title":{"rendered":"Prefeitura j\u00e1 recolheu \u20287 toneladas de fios"},"content":{"rendered":"<div class='code-block code-block-1' style='margin: 8px 0 8px auto; text-align: right; display: block; clear: both;'>\n<p><a href=\"https:\/\/wa.link\/vpicfd\"><img data-recalc-dims=\"1\" class=\"wp-image-4922\" style=\"aspect-ratio: 2.0253164556962027; width: 561px; height: auto;\" src=\"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/grupo-de-empregos-whatsapp-e-facebook-ismael-colosi-vagas.jpg?ssl=1\" alt=\"\" \/><\/a><\/p>\n<!-- \/wp:image -->\n<\/div>\n<p> <br \/>\n<\/p>\n<div>\n<p class=\"p1\">A prefeitura de Ribeir\u00e3o Preto, por meio da Secretaria de Infraestrutura e Zeladoria, recolheu de janeiro a abril deste ano, cerca de sete toneladas de fios inutilizados e das ruas e avenidas da cidade. Em 2025, entre os meses de mar\u00e7o e dezembro, o total chegou a 67 toneladas de materiais retirados.<\/p>\n<p>Desde segunda-feira, 11 de maio, as opera\u00e7\u00f5es de regulariza\u00e7\u00e3o e retirada de cabos inutilizados de telecomunica\u00e7\u00f5es est\u00e3o sendo realizadas no Jardim S\u00e3o Lu\u00eds, na regi\u00e3o Sul da cidade. Ap\u00f3s a conclus\u00e3o dos servi\u00e7os no Jardim S\u00e3o Lu\u00eds, as equipes seguir\u00e3o para os bairros Parque Ribeir\u00e3o Preto e Vila Virg\u00ednia, ambos localizados na Zona Oeste.<\/p>\n<p>\u201cOs fios soltos e sem utiliza\u00e7\u00e3o foram identificados em diferentes regi\u00f5es da cidade. No ano passado realizamos um amplo trabalho de limpeza e agora estamos dando continuidade a essa a\u00e7\u00e3o, com equipes concentradas por bairros para otimizar os servi\u00e7os, al\u00e9m dos atendimentos emergenciais e pontuais. Os resultados t\u00eam sido bastante positivos\u201d, afirma o secret\u00e1rio de Infraestrutura e Zeladoria, Claudio Almeida.<\/p>\n<p>Os trabalhos s\u00e3o coordenados pela Secretaria de Infraestrutura e Zeladoria, por meio da Comiss\u00e3o de Infraestrutura A\u00e9rea de Ribeir\u00e3o Preto (Coinfarp). A opera\u00e7\u00e3o \u00e9 executada em conjunto pela CPFL Paulista e pelas empresas de telecomunica\u00e7\u00f5es respons\u00e1veis pelos cabos instalados nos postes de energia el\u00e9trica.<\/p>\n<p>No come\u00e7o de mar\u00e7o, o prefeito Ricardo Silva (PSD) encaminhou para a C\u00e2mara de Vereadores, o veto total ao projeto de lei aprovado pelos parlamentares, que pretendia endurecer as medidas de combate ao furto e recepta\u00e7\u00e3o de fios, cabos e materiais met\u00e1licos de origem il\u00edcita e que estabelecia multas elevadas para os infratores.<\/p>\n<p>De autoria do vereador Danilo Scochi (MDB) o projeto de lei foi aprovado no dia 9 de fevereiro, A proposta atacava diretamente a cadeia comercial que sustenta os crimes de furtos e roubos de fios. Estabelecia que pessoas f\u00edsicas ou jur\u00eddicas que fossem flagradas em recepta\u00e7\u00e3o destes materiais seriam multados em at\u00e9 R$ 300 mil, valor que dobraria em caso de reincid\u00eancia.<\/p>\n<p>Al\u00e9m da puni\u00e7\u00e3o financeira, as empresas infratoras seriam lacradas imediatamente e poderiam ter a cassa\u00e7\u00e3o definitiva do alvar\u00e1 e a proibi\u00e7\u00e3o de contratar com o Poder P\u00fablico por um per\u00edodo de dez anos.<\/p>\n<p>O veto a proposta foi acolhido pelos vereadores, mas Danilo Scochi protocolou um novo projeto reduzindo a multa para R$ 150 mil. Atualmente a proposta est\u00e1 na Comiss\u00e3o de Constitui\u00e7\u00e3o, Justi\u00e7a e Reda\u00e7\u00e3o (CCJ) aguardando parecer.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/prefeitura-ja-recolheu-7-toneladas-de-fios\/\">Texto original daqui <\/a><\/p>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>A prefeitura de Ribeir\u00e3o Preto, por meio da Secretaria de Infraestrutura e Zeladoria, recolheu de janeiro a abril deste ano, cerca de sete toneladas de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":85641,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11],"tags":[5473,292,244,6637,939],"class_list":["post-85640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-fios","tag-ja","tag-prefeitura","tag-recolheu","tag-toneladas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/05\/FiacaoRP-Fernando-Gonzaga-scaled.jpg?fit=1170%2C780&ssl=1","jetpack-related-posts":[{"id":70256,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/05\/24\/fios-soltos-serao-retirados-em-junho\/","url_meta":{"origin":85640,"position":0},"title":"Fios soltos ser\u00e3o retirados em junho\u00a0","author":"noticiasribeiraopreto.com.br","date":"24 de May de 2025","format":false,"excerpt":"24 de maio de 2025 09:3023 de maio de 2025 18:469 Compartilhar0 A prefeitura de Ribeir\u00e3o Preto, por meio da Comiss\u00e3o de Infraestrutura A\u00e9rea (Coinfarp) da Secretaria Municipal de Infraestrutura, definiu o cronograma de regulariza\u00e7\u00e3o dos fios soltos de internet e telefonia na regi\u00e3o Central da cidade.\u00a0 A primeira etapa\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/FiacaoRP-Divulgacao.jpg?fit=1000%2C666&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/FiacaoRP-Divulgacao.jpg?fit=1000%2C666&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/FiacaoRP-Divulgacao.jpg?fit=1000%2C666&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/FiacaoRP-Divulgacao.jpg?fit=1000%2C666&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":71883,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/06\/11\/operacao-recolhe-1-t-de-fios\/","url_meta":{"origin":85640,"position":1},"title":"Opera\u00e7\u00e3o recolhe 1 t de fios","author":"noticiasribeiraopreto.com.br","date":"11 de June de 2025","format":false,"excerpt":"Em apenas uma semana de opera\u00e7\u00e3o, mais de uma tonelada de cabos irregulares, inoperantes ou fora dos padr\u00f5es t\u00e9cnicos foi retirada dos postes localizados no Centro de Ribeir\u00e3o Preto pelas operadoras de telecomunica\u00e7\u00e3o. A a\u00e7\u00e3o \u00e9 realizada com o apoio e acompanhamento da CPFL Paulista. A concession\u00e1ria conduz o processo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/FiacaoRP-Divulgacao-CPFL-Energia-01.png?fit=377%2C500&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":66448,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/04\/01\/jornal-da-franca-arrastao-da-dengue-tem-7-toneladas-de-lixo-retiradas-no-jardim-tropical\/","url_meta":{"origin":85640,"position":2},"title":"Jornal da Franca &#8211; Arrast\u00e3o da Dengue tem 7 toneladas de lixo retiradas no Jardim Tropical","author":"noticiasribeiraopreto.com.br","date":"1 de April de 2025","format":false,"excerpt":"compartilhar no whatsapp compartilhar no telegram compartilhar no facebook compartilhar no linkedin No \u00faltimo s\u00e1bado, um grande mutir\u00e3o de limpeza passou pelo Jardim Tropical e recolheu mais de 7 toneladas de entulhos e materiais inserv\u00edveis No \u00faltimo s\u00e1bado, 29, equipes do Arrast\u00e3o da Dengue percorreram as ruas do bairro Jardim\u2026","rel":"","context":"In &quot;Not\u00edcias de Franca-SP&quot;","block_context":{"text":"Not\u00edcias de Franca-SP","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/noticias-franca-sp\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/04\/Arrastao-da-Dengue.jpeg?fit=1032%2C502&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/04\/Arrastao-da-Dengue.jpeg?fit=1032%2C502&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/04\/Arrastao-da-Dengue.jpeg?fit=1032%2C502&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/04\/Arrastao-da-Dengue.jpeg?fit=1032%2C502&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":70215,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/05\/23\/saiba-quando-comeca-a-regularizacao-dos-fios-soltos-no-centro-de-ribeirao-preto\/","url_meta":{"origin":85640,"position":3},"title":"Saiba quando come\u00e7a a regulariza\u00e7\u00e3o dos fios soltos no Centro de Ribeir\u00e3o Preto","author":"noticiasribeiraopreto.com.br","date":"23 de May de 2025","format":false,"excerpt":"A Prefeitura de Ribeir\u00e3o Preto, por meio da Secretaria de Infraestrutura, vai come\u00e7ar a regulariza\u00e7\u00e3o dos fios soltos de internet e telefonia na regi\u00e3o central no dia 2 de junho. A iniciativa visa eliminar os cabos soltos e desorganizados que representam riscos para pedestres e ve\u00edculos. A primeira etapa acontecer\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/design_sem_nome_x30x.jpg?fit=1200%2C603&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/design_sem_nome_x30x.jpg?fit=1200%2C603&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/design_sem_nome_x30x.jpg?fit=1200%2C603&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/design_sem_nome_x30x.jpg?fit=1200%2C603&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/05\/design_sem_nome_x30x.jpg?fit=1200%2C603&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":53850,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2024\/06\/25\/caminhao-arranca-fios-em-rua-de-ribeirao-preto-assista-ao-video\/","url_meta":{"origin":85640,"position":4},"title":"Caminh\u00e3o arranca fios em rua de Ribeir\u00e3o Preto; Assista ao v\u00eddeo","author":"noticiasribeiraopreto.com.br","date":"25 de June de 2024","format":false,"excerpt":"Um caminh\u00e3o que transportava uma m\u00e1quina danificou a fia\u00e7\u00e3o na rua General Os\u00f3rio, nesta segunda-feira (24), ao enroscar nos cabos a partir da avenida Independ\u00eancia, na Vila Seixas, em Ribeir\u00e3o Preto. Assista ao v\u00eddeo abaixo. A CPFL Paulista informou que, al\u00e9m dos fios da rede el\u00e9trica e um poste, cabos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/06\/CAMINHAO-FIOS_2024-06-25_15-00-46_jpg_2024-06-25_15-00-46.webp.webp?fit=1200%2C781&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/06\/CAMINHAO-FIOS_2024-06-25_15-00-46_jpg_2024-06-25_15-00-46.webp.webp?fit=1200%2C781&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/06\/CAMINHAO-FIOS_2024-06-25_15-00-46_jpg_2024-06-25_15-00-46.webp.webp?fit=1200%2C781&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/06\/CAMINHAO-FIOS_2024-06-25_15-00-46_jpg_2024-06-25_15-00-46.webp.webp?fit=1200%2C781&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/06\/CAMINHAO-FIOS_2024-06-25_15-00-46_jpg_2024-06-25_15-00-46.webp.webp?fit=1200%2C781&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1389,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2023\/11\/12\/campanha-recolhe-cartelas-de-medicamento-vazias\/","url_meta":{"origin":85640,"position":5},"title":"Campanha recolhe cartelas de medicamento vazias","author":"noticiasribeiraopreto.com.br","date":"12 de November de 2023","format":false,"excerpt":"12 de novembro de 2023 | 14:0011 de novembro de 2023 | 17:29 0A campanha Civilidade nas Ruas, idealizada pela Associa\u00e7\u00e3o de Engenharia, Arquitetura e Agronomia de Ribeir\u00e3o Preto (AEAARP) recolheu 4,5 toneladas de res\u00edduos no m\u00eas de outubro. Foram coletadas 2,5 toneladas de papel\/papel\u00e3o, 300kg de latinha, 600kg de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2023\/11\/fotoblister-creditodivulgacao.jpg?fit=735%2C380&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2023\/11\/fotoblister-creditodivulgacao.jpg?fit=735%2C380&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2023\/11\/fotoblister-creditodivulgacao.jpg?fit=735%2C380&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2023\/11\/fotoblister-creditodivulgacao.jpg?fit=735%2C380&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peQAOb-mhi","_links":{"self":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/85640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=85640"}],"version-history":[{"count":0,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/85640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/media\/85641"}],"wp:attachment":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=85640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=85640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=85640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}