{"id":88172,"date":"2026-07-15T15:12:06","date_gmt":"2026-07-15T18:12:06","guid":{"rendered":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/15\/the-moscow-ballet-apresenta-gala-concert-em-ribeirao-preto-veja-como-comprar-ingressos\/"},"modified":"2026-07-15T15:12:06","modified_gmt":"2026-07-15T18:12:06","slug":"the-moscow-ballet-apresenta-gala-concert-em-ribeirao-preto-veja-como-comprar-ingressos","status":"publish","type":"post","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/15\/the-moscow-ballet-apresenta-gala-concert-em-ribeirao-preto-veja-como-comprar-ingressos\/","title":{"rendered":"The Moscow Ballet apresenta \u2018Gala Concert\u2019 em Ribeir\u00e3o Preto; Veja como comprar ingressos"},"content":{"rendered":"<div class='code-block code-block-1' style='margin: 8px 0 8px auto; text-align: right; display: block; clear: both;'>\n<p><a href=\"https:\/\/wa.link\/vpicfd\"><img data-recalc-dims=\"1\" class=\"wp-image-4922\" style=\"aspect-ratio: 2.0253164556962027; width: 561px; height: auto;\" src=\"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/grupo-de-empregos-whatsapp-e-facebook-ismael-colosi-vagas.jpg?ssl=1\" alt=\"\" \/><\/a><\/p>\n<!-- \/wp:image -->\n<\/div>\n<p> <br \/>\n<\/p>\n<p><strong>Ribeir\u00e3o Preto<\/strong> recebe, nos dias <strong>30 e 31 de julho<\/strong>, o <strong>espet\u00e1culo &#8220;Gala Concert&#8221;<\/strong>, da <strong>companhia The Moscow Ballet<\/strong>. A apresenta\u00e7\u00e3o ser\u00e1 no <strong>Theatro Pedro II, \u00e0s 20h<\/strong>. <\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">A produ\u00e7\u00e3o, liderada pela bailarina Oksana Bondareva, vencedora do Pr\u00eamio Capri 2025, busca interpretar trechos e varia\u00e7\u00f5es inspirados em cl\u00e1ssicos que atravessaram gera\u00e7\u00f5es e consolidaram o bal\u00e9. Ao lado da bailarina, estar\u00e3o em cena oito solistas internacionais de companhias europeias tradicionais.<\/mark><\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><figcaption class=\"wp-element-caption\">The Moscow Ballet traz a Ribeir\u00e3o Preto o espet\u00e1culo &#8216;Gala Concert&#8217; &#8211; Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"621\" data-id=\"165956\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2026\/07\/Bale-retorna-a-Ribeirao-Preto-com-espetaculo-Gala-Concert-3-1-1024x621.jpeg?resize=1024%2C621&#038;ssl=1\" alt=\"The Moscow Ballet\" class=\"wp-image-165956\" title=\"The Moscow Ballet apresenta &apos;Gala Concert&apos; em Ribeir\u00e3o Preto; Veja como comprar ingressos 5\" \/><figcaption class=\"wp-element-caption\">The Moscow Ballet traz a Ribeir\u00e3o Preto o espet\u00e1culo &#8216;Gala Concert&#8217; &#8211; Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<\/figure>\n<p class=\"has-cyan-bluish-gray-background-color has-background\"><em>Receba not\u00edcias do&nbsp;<strong>acidade on Ribeir\u00e3o&nbsp;<\/strong>no WhatsApp e fique por dentro de tudo! Basta acessar o link<a href=\"https:\/\/chat.whatsapp.com\/DfXwcjKVIddHUT3BvnQuPZ?mode=hqctshi\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;aqu<\/a>i!<\/em><\/p>\n<h2 class=\"wp-block-heading\">Repert\u00f3rio re\u00fane v\u00e1rias obras<\/h2>\n<p>O repert\u00f3rio da edi\u00e7\u00e3o deste ano re\u00fane diferentes \u00e9pocas, estilos e tradi\u00e7\u00f5es da dan\u00e7a. Entre os destaques est\u00e3o trechos de obras como &#8220;<strong>A Bela Adormecida<\/strong>,&#8221; &#8220;<strong>O Lago dos Cisnes<\/strong>,&#8221; &#8220;<strong>Raymonda<\/strong>,&#8221; &#8220;<strong>O Cors\u00e1rio<\/strong>,&#8221; &#8220;<strong>Carnaval em Veneza<\/strong>&#8221; e &#8220;<strong>La Sylphide<\/strong>.&#8221;<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>\u201cOs espectadores poder\u00e3o mergulhar na era de ouro do bal\u00e9. Ser\u00e1 uma viagem no tempo atrav\u00e9s da dan\u00e7a, sem limites para a imagina\u00e7\u00e3o\u201d<\/strong>, conta Oksana Bondareva, que tamb\u00e9m \u00e9 respons\u00e1vel pela dire\u00e7\u00e3o art\u00edstica do espet\u00e1culo, junto a Andrey Lyapin.<\/p>\n<\/blockquote>\n<h2 class=\"wp-block-heading\">Bal\u00e9 busca superar limites do corpo <\/h2>\n<p>Os c\u00e9lebres e complexos <strong>pas de deux<\/strong>, tradicionais duetos do bal\u00e9 cl\u00e1ssico, devem contar com bailarinos que buscam desafiar os limites do corpo humano com saltos, giros e movimentos que exigem dom\u00ednio da t\u00e9cnica cl\u00e1ssica.<\/p>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"551\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2026\/07\/Capa-Bale-retorna-a-Ribeirao-Preto-com-espetaculo-Gala-Concert-2-1024x551.jpeg?resize=1024%2C551&#038;ssl=1\" alt=\"The Moscow Ballet\" class=\"wp-image-165944\" title=\"The Moscow Ballet apresenta &apos;Gala Concert&apos; em Ribeir\u00e3o Preto; Veja como comprar ingressos 6\" \/><figcaption class=\"wp-element-caption\">Apresenta\u00e7\u00e3o busca superar limites do corpo humano &#8211; Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<h2 class=\"wp-block-heading\">Companhia decidiu retornar ao Brasil<\/h2>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Oksana explica o motivo de voltar ao pa\u00eds depois da turn\u00ea realizada no ano passado <strong>\u201cO Brasil \u00e9 um dos poucos pa\u00edses onde a emo\u00e7\u00e3o \u00e9 demonstrada de forma t\u00e3o intensa. As pessoas fazem quest\u00e3o de agradecer, e isso nos toca profundamente. Esse carinho \u00e9 um grande incentivo para n\u00f3s\u201d<\/strong>, destaca a bailarina. <\/p>\n<\/blockquote>\n<p>Al\u00e9m de Ribeir\u00e3o Preto, a turn\u00ea passa por munic\u00edpios como Campinas e Piracicaba.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"534\" data-id=\"165951\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2026\/07\/Bale-retorna-a-Ribeirao-Preto-com-espetaculo-Gala-Concert-4-1024x534.jpeg?resize=1024%2C534&#038;ssl=1\" alt=\"The Moscow Ballet\" class=\"wp-image-165951\" title=\"The Moscow Ballet apresenta &apos;Gala Concert&apos; em Ribeir\u00e3o Preto; Veja como comprar ingressos 7\" \/><figcaption class=\"wp-element-caption\">The Moscow Ballet traz a Ribeir\u00e3o Preto o espet\u00e1culo &#8216;Gala Concert&#8217; &#8211; Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"515\" data-id=\"165952\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2026\/07\/Bale-retorna-a-Ribeirao-Preto-com-espetaculo-Gala-Concert-2-1024x515.jpeg?resize=1024%2C515&#038;ssl=1\" alt=\"The Moscow Ballet\" class=\"wp-image-165952\" title=\"The Moscow Ballet apresenta &apos;Gala Concert&apos; em Ribeir\u00e3o Preto; Veja como comprar ingressos 8\" \/><figcaption class=\"wp-element-caption\">The Moscow Ballet traz a Ribeir\u00e3o Preto o espet\u00e1culo &#8216;Gala Concert&#8217; &#8211; Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<\/figure>\n<h2 class=\"wp-block-heading\">Servi\u00e7o<\/h2>\n<p><em>&#8220;Gala Concert&#8221;, com a companhia The Moscow Ballet<\/em><\/p>\n<p><strong>Datas: <\/strong>30 e 31 de julho<br \/><strong>Hor\u00e1rio:<\/strong> 20h<br \/><strong>Local:<\/strong> Theatro Pedro II \u2013 Rua \u00c1lvares Cabral, 370, Centro \u2013 Ribeir\u00e3o Preto<br \/><strong>Classifica\u00e7\u00e3o et\u00e1ria: <\/strong>Menores de 14 anos devem estar acompanhados pelos pais ou respons\u00e1veis.<br \/><strong>Ingressos: <\/strong>A partir de R$ 140,00<\/p>\n<h2 class=\"wp-block-heading\">Links para compra<\/h2>\n<p><a href=\"https:\/\/www.ingressonacional.com.br\/evento\/33362\/gala-concert-----the-moscow-ballet-com-oksana-bondareva--30-07\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a> para ingressos do dia 30 (quinta-feira)<br \/><a href=\"https:\/\/www.ingressonacional.com.br\/evento\/33363\/gala-concert-----the-moscow-ballet-com-oksana-bondareva--31-07\" target=\"_blank\" rel=\"noopener\">Clique aqui<\/a> para ingressos do dia 31 (sexta-feira)<\/p>\n<p>Os port\u00f5es devem ser abertos \u00e0s 19h. <strong>N\u00e3o ser\u00e1 permitido menores de 12 anos na Fila A dos setores Balc\u00e3o Nobre e Balc\u00e3o Simples, por conta de quest\u00f5es de seguran\u00e7a<\/strong>. <strong>Menores de 14 anos devem assistir ao bal\u00e9 acompanhados dos pais ou respons\u00e1veis<\/strong>.<\/p>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"504\" src=\"https:\/\/i0.wp.com\/www.acidadeon.com\/ribeiraopreto\/wp-content\/uploads\/sites\/3\/2026\/07\/Bale-retorna-a-Ribeirao-Preto-com-espetaculo-Gala-Concert-5-1-1024x504.jpeg?resize=1024%2C504&#038;ssl=1\" alt=\"Bal\u00e9\" class=\"wp-image-165953\" title=\"The Moscow Ballet apresenta &apos;Gala Concert&apos; em Ribeir\u00e3o Preto; Veja como comprar ingressos 9\" \/><figcaption class=\"wp-element-caption\">Bal\u00e9 apresenta em Ribeir\u00e3o Preto o espet\u00e1culo &#8216;Gala Concert&#8217; &#8211; Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p class=\"has-cyan-bluish-gray-background-color has-background\"><em>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre&nbsp;<strong>Ribeir\u00e3o Preto&nbsp;<\/strong>e regi\u00e3o por meio do WhatsApp do&nbsp;<strong>acidade on Ribeir\u00e3o<\/strong>: (16) 99117-7802.<\/em><\/p>\n<p>O post The Moscow Ballet apresenta &#8216;Gala Concert&#8217; em Ribeir\u00e3o Preto; Veja como comprar ingressos apareceu primeiro em ACidade ON Ribeir\u00e3o Preto.<\/p>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/the-moscow-ballet-apresenta-gala-concert-em-ribeirao-preto-veja-como-comprar-ingressos\/\">Link para o texto original aqui <\/a><\/p>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Ribeir\u00e3o Preto recebe, nos dias 30 e 31 de julho, o espet\u00e1culo &#8220;Gala Concert&#8221;, da companhia The Moscow Ballet. A apresenta\u00e7\u00e3o ser\u00e1 no Theatro Pedro&#8230;<\/p>\n","protected":false},"author":1,"featured_media":88173,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[56,3230,265,2687,3770,7740,370,7739,27,26,7738,48],"class_list":["post-88172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-apresenta","tag-ballet","tag-como","tag-comprar","tag-concert","tag-gala","tag-ingressos","tag-moscow","tag-preto","tag-ribeirao","tag-the-moscow","tag-veja"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/Bale-retorna-a-Ribeirao-Preto-com-espetaculo-Gala-Concert.jpeg?fit=1599%2C826&ssl=1","jetpack-related-posts":[{"id":72826,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/06\/21\/bale-russo-apresenta-gala-concert-em-ribeirao-preto-veja-como-comprar-ingressos\/","url_meta":{"origin":88172,"position":0},"title":"Bal\u00e9 russo apresenta &#8216;Gala Concert&#8217; em Ribeir\u00e3o Preto; veja como comprar ingressos","author":"noticiasribeiraopreto.com.br","date":"21 de June de 2025","format":false,"excerpt":"A companhia de bal\u00e9 russa, The Moscow Ballet se apresenta na pr\u00f3xima quinta-feira (3), no Theatro Pedro II, localizado no Centro de Ribeir\u00e3o Preto, com o espet\u00e1culo \u201cGala Concert\u201d. Os ingressos ainda est\u00e3o dispon\u00edveis e podem ser adquiridos tanto on-line quanto presencialmente. \u2013 veja como abaixo como garantir o seu.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/Captura-de-tela-2025-06-18-201356-1.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/Captura-de-tela-2025-06-18-201356-1.webp.webp?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/Captura-de-tela-2025-06-18-201356-1.webp.webp?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/Captura-de-tela-2025-06-18-201356-1.webp.webp?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/Captura-de-tela-2025-06-18-201356-1.webp.webp?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":80412,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/12\/03\/musical-o-quebra-nozes-chega-a-ribeirao-preto-com-o-the-moscow-ballet-veja-quando\/","url_meta":{"origin":88172,"position":1},"title":"Musical \u2018O Quebra-Nozes\u2019 chega a Ribeir\u00e3o Preto com o The Moscow Ballet; veja quando","author":"noticiasribeiraopreto.com.br","date":"3 de December de 2025","format":false,"excerpt":"O cl\u00e1ssico natalino O Quebra-Nozes retorna aos palcos de Ribeir\u00e3o Preto nesta ter\u00e7a (2) e quarta-feira (3) de dezembro. O p\u00fablico poder\u00e1 assistir a duas montagens diferentes: a vers\u00e3o internacional apresentada pela The Moscow Ballet, no Theatro Pedro II. O musical A montagem traz ao palco bailarinos internacionais \u2014 com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2025-11-28T202412.103_2025-11-28_23-24-18.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2025-11-28T202412.103_2025-11-28_23-24-18.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2025-11-28T202412.103_2025-11-28_23-24-18.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2025-11-28T202412.103_2025-11-28_23-24-18.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2025-11-28T202412.103_2025-11-28_23-24-18.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":31313,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2024\/01\/21\/theatro-pedro-ii-recebe-o-musical-rei-leao-in-concert-veja-como-comprar-ingressos\/","url_meta":{"origin":88172,"position":2},"title":"Theatro Pedro II recebe o musical \u2018Rei Le\u00e3o In Concert\u2019; Veja como comprar ingressos","author":"noticiasribeiraopreto.com.br","date":"21 de January de 2024","format":false,"excerpt":"O Theatro Pedro II, em Ribeir\u00e3o Preto, recebe o musical \u201cRei Le\u00e3o In Concert\u201d, no pr\u00f3ximo dia 10 de mar\u00e7o. Os ingressos para o espet\u00e1culo podem ser comprados pela internet e custam entre R$ 55 e R$ 150. O musical conta com o recurso de proje\u00e7\u00e3o mapeada 3D e os\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/01\/reileao.jpg?fit=978%2C613&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/01\/reileao.jpg?fit=978%2C613&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/01\/reileao.jpg?fit=978%2C613&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/01\/reileao.jpg?fit=978%2C613&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":79278,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/10\/28\/ribeirao-preto-recebe-espetaculo-internacional-de-o-quebra-nozes-no-theatro-pedro-ii\/","url_meta":{"origin":88172,"position":3},"title":"Ribeir\u00e3o Preto recebe espet\u00e1culo internacional de \u2018O Quebra-Nozes\u2019 no Theatro Pedro II","author":"noticiasribeiraopreto.com.br","date":"28 de October de 2025","format":false,"excerpt":"Ribeir\u00e3o Preto recebe nos dias 2 e 3 de dezembro, \u00e0s 20h, no Theatro Pedro II, uma montagem do bal\u00e9 cl\u00e1ssico O Quebra-Nozes. O espet\u00e1culo contar\u00e1 com a participa\u00e7\u00e3o de Oksana Bondareva, solista do Teatro Mariinsky, e do italiano Leonardo de Checchi, ambos premiados recentemente no Capri Danza International 2025.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/10\/voguing-3_2025-10-28_21-12-44.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/10\/voguing-3_2025-10-28_21-12-44.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/10\/voguing-3_2025-10-28_21-12-44.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/10\/voguing-3_2025-10-28_21-12-44.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/10\/voguing-3_2025-10-28_21-12-44.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48916,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2024\/05\/07\/humberto-gessinger-se-apresenta-em-ribeirao-preto-veja-como-comprar-ingressos\/","url_meta":{"origin":88172,"position":4},"title":"Humberto Gessinger se apresenta em Ribeir\u00e3o Preto; Veja como comprar ingressos","author":"noticiasribeiraopreto.com.br","date":"7 de May de 2024","format":false,"excerpt":"O cantor Humberto Gessinger, antigo vocalista e l\u00edder da banda Engenheiros do Hawaii, traz para os palcos do Theatro Pedro II, em Ribeir\u00e3o Preto, o show de sua turn\u00ea \u201cQuatro Cantos de Um Mundo Redondo\u201c, no dia 20 de outubro, \u00e0s 19h. Nas dez faixas do \u00e1lbum, Humberto Gessinger convida\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/05\/humberto-gessinger_2024-05-07_12-41-18_jpg_2024-05-07_12-41-18.webp.webp?fit=700%2C466&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/05\/humberto-gessinger_2024-05-07_12-41-18_jpg_2024-05-07_12-41-18.webp.webp?fit=700%2C466&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/05\/humberto-gessinger_2024-05-07_12-41-18_jpg_2024-05-07_12-41-18.webp.webp?fit=700%2C466&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/05\/humberto-gessinger_2024-05-07_12-41-18_jpg_2024-05-07_12-41-18.webp.webp?fit=700%2C466&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":66530,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/04\/02\/renato-teixeira-se-apresenta-no-projeto-starlight-concert-em-ribeirao-preto\/","url_meta":{"origin":88172,"position":5},"title":"Renato Teixeira se apresenta no projeto \u2018Starlight Concert\u2019 em Ribeir\u00e3o Preto","author":"noticiasribeiraopreto.com.br","date":"2 de April de 2025","format":false,"excerpt":"O cantor Renato Teixeira se apresenta no projeto Starlight Concerts, no Theatro Pedro II, em Ribeir\u00e3o Preto, no pr\u00f3ximo s\u00e1bado (5), \u00e0s 20h. Os ingressos ainda podem ser adquiridos na bilheteria ou on-line. O projeto Starlight Concerts transforma completamente o espa\u00e7o do teatro, criando uma sensa\u00e7\u00e3o de estar sob um\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-08-27_17-18-18_jpg_2024-08-27_17-18-18.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-08-27_17-18-18_jpg_2024-08-27_17-18-18.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-08-27_17-18-18_jpg_2024-08-27_17-18-18.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-08-27_17-18-18_jpg_2024-08-27_17-18-18.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-08-27_17-18-18_jpg_2024-08-27_17-18-18.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peQAOb-mW8","_links":{"self":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/88172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=88172"}],"version-history":[{"count":0,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/88172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/media\/88173"}],"wp:attachment":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=88172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=88172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=88172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}