{"id":88370,"date":"2026-07-18T11:35:34","date_gmt":"2026-07-18T14:35:34","guid":{"rendered":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/18\/comercial-estreia-na-copa-paulista-contra-noroeste\/"},"modified":"2026-07-18T11:35:34","modified_gmt":"2026-07-18T14:35:34","slug":"comercial-estreia-na-copa-paulista-contra-noroeste","status":"publish","type":"post","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/18\/comercial-estreia-na-copa-paulista-contra-noroeste\/","title":{"rendered":"Comercial estreia na Copa Paulista contra Noroeste"},"content":{"rendered":"<div class='code-block code-block-1' style='margin: 8px 0 8px auto; text-align: right; display: block; clear: both;'>\n<p><a href=\"https:\/\/wa.link\/vpicfd\"><img data-recalc-dims=\"1\" class=\"wp-image-4922\" style=\"aspect-ratio: 2.0253164556962027; width: 561px; height: auto;\" src=\"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/grupo-de-empregos-whatsapp-e-facebook-ismael-colosi-vagas.jpg?ssl=1\" alt=\"\" \/><\/a><\/p>\n<!-- \/wp:image -->\n<\/div>\n<p> <br \/>\n<\/p>\n<div>\n<p><strong><em>Por Hugo Luque<\/em><\/strong><\/p>\n<p>O Comercial estreia na Copa Paulista neste s\u00e1bado (18), \u00e0s 16h, no Est\u00e1dio Palma Travassos, contra o Noroeste. No primeiro duelo do Grupo 2, o Le\u00e3o do Norte quer come\u00e7ar sua jornada no torneio com o \u201cp\u00e9 direito\u201d para que o novo elenco ganhe confian\u00e7a na briga pela classifica\u00e7\u00e3o ao mata-mata.<\/p>\n<p>Mas n\u00e3o \u00e9 s\u00f3 dentro de campo que o Bafo passou por mudan\u00e7as. Nos 105 dias que separam o \u00faltimo jogo da equipe na S\u00e9rie A4 do Campeonato Paulista da estreia na Copa Paulista, houve troca de presidente, dois gerentes de futebol diferentes e o retorno de Raphael Pereira ao comando t\u00e9cnico, agora com Osny, at\u00e9 ent\u00e3o treinador, novamente como auxiliar.<\/p>\n<p>Durante o m\u00eas de meio de intertemporada, que teve largada no in\u00edcio de junho, o Comercial realizou quatro jogos-treino. Foram duas vit\u00f3rias, diante do sub-20 do Bafo e do I9, e duas derrotas para o Mar\u00edlia. Apesar dos trope\u00e7os nos amistosos mais recentes, Pereira elogiou a minuciosa prepara\u00e7\u00e3o alvinegra e acredita que esse per\u00edodo de treinos pode fazer a diferen\u00e7a nas partidas oficiais.<\/p>\n<p>\u201cNosso advers\u00e1rio vem de uma sequ\u00eancia de jogos muito boa na S\u00e9rie D do Brasileiro, mas nossa prepara\u00e7\u00e3o foi ideal. A gente seguiu todos os protocolos em rela\u00e7\u00e3o ao prazo para fazer todas as fases, trabalhando as quest\u00f5es f\u00edsicas e a evolu\u00e7\u00e3o. Alguns atletas chegaram nesta semana, mas j\u00e1 em n\u00edvel bom fisicamente, ent\u00e3o n\u00e3o vamos ter problema nenhum na nossa estreia. A prepara\u00e7\u00e3o foi bem feita para a gente iniciar com o p\u00e9 direito\u201d, destacou.<\/p>\n<p>Enquanto o Le\u00e3o est\u00e1 sem entrar em campo por um jogo de campeonato desde a vit\u00f3ria por 2 a 1 sobre o Tanabi, em 4 de abril, o Noroeste ocupou seu intervalo entre elite do Paulist\u00e3o e Copa Paulista com a S\u00e9rie D. Vice-l\u00edder de sua chave na fase de grupos do nacional, o Norusca caiu no primeiro mata-mata diante da Portuguesa-RJ, no fim de junho. Nos \u00faltimos cinco compromissos, foram uma vit\u00f3ria, dois empates e duas derrotas.<\/p>\n<p>Na hist\u00f3ria do embate paulista, a vantagem \u00e9 dos bauruenses, que venceram 22 vezes e perderam 17, al\u00e9m de 19 empates. No encontro mais recente, pela S\u00e9rie A2 de 2024, igualdade em 1 a 1. O \u00faltimo triunfo ribeir\u00e3o-pretano foi em 2020, fora de casa, pela S\u00e9rie A3, por 3 a 2.<\/p>\n<h2><strong>Novo elenco<\/strong><\/h2>\n<p>Foram contratados para esta Copa Paulista os goleiros Jefferson Castro, Lee Winston e Matheus Pellegrini, os zagueiros Luc\u00e3o e Bruno Miranda, os laterais Lu\u00eds Fernando, Ricardo Fran\u00e7a, Luiz Paim e Samuel Balbino, os volantes Anderson Balbino, L\u00e9o Couto, Matheus Felipe e Jo\u00e3o Pedro, os meias L\u00e9o Cereja, Filipinho, Edgar Neto e Thalis, al\u00e9m dos atacantes Danilo Alves, Gustavo Henrique e Coutinho. Outros cinco jogadores permaneceram ap\u00f3s a A4.<\/p>\n<p>A escala\u00e7\u00e3o para a estreia ainda \u00e9 um mist\u00e9rio, mas um poss\u00edvel time titular tem: Lee Winston; Lu\u00eds Fernando, Bruno Miranda (Luc\u00e3o), Cristopher e Samuel Balbino; L\u00e9o Couto, Anderson Balbino (Jo\u00e3o Pedro) e Filipinho (L\u00e9o Cereja ou Edgar Neto); Coutinho, Gustavo Henrique e Paulo Victor (Danilo Alves).<\/p>\n<p>Os ingressos para a partida deste s\u00e1bado est\u00e3o \u00e0 venda por R$ 40 a inteira e R$ 20 a meia-entrada. Torcedor com camisa do Comercial tamb\u00e9m paga metade do pre\u00e7o. As equipes est\u00e3o no Grupo 2 da Copa Paulista, ao lado de XV de Piracicaba e Uni\u00e3o S\u00e3o Jo\u00e3o.<\/p>\n<div style=\"background-color: #f4f4f5; border: 1px solid #d4d4d8; padding: 15px; margin: 20px 0; border-radius: 6px; font-family: sans-serif; line-height: 1.5;\">\n    <span style=\"color: #27272a;\">Inscreva-se em nosso Canal no Whatsapp e fique por dentro de tudo que acontece na regi\u00e3o. <\/span><br \/>\n    <a href=\"https:\/\/whatsapp.com\/channel\/0029VanuE2o7z4kYjo0XVS3u\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color: #16a34a; font-weight: bold; text-decoration: underline;\">Clique Aqui!<\/a>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/comercial-estreia-na-copa-paulista-contra-noroeste\/\">Texto original daqui <\/a><\/p>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>Por Hugo Luque O Comercial estreia na Copa Paulista neste s\u00e1bado (18), \u00e0s 16h, no Est\u00e1dio Palma Travassos, contra o Noroeste. No primeiro duelo do&#8230;<\/p>\n","protected":false},"author":1,"featured_media":88371,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[705,109,707,1785,3992,762],"class_list":["post-88370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-comercial","tag-contra","tag-copa","tag-estreia","tag-noroeste","tag-paulista"],"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":88394,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/18\/comercial-vence-o-noroeste-e-estreia-com-vitoria-na-copa-paulista-2026\/","url_meta":{"origin":88370,"position":0},"title":"Comercial vence o Noroeste e estreia com vit\u00f3ria na Copa Paulista 2026","author":"noticiasribeiraopreto.com.br","date":"18 de July de 2026","format":false,"excerpt":"O Comercial venceu o Noroeste por 2 a 0 na tarde deste s\u00e1bado (18), no est\u00e1dio Palma Travassos, em Ribeir\u00e3o Preto, pela primeira rodada da Copa Paulista 2026. Os dois gols da equipe de Ribeir\u00e3o Preto sa\u00edram no segundo tempo. O atacante Paulo Vitor, camisa 9 do Bafo, balan\u00e7ou as\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/image-31.png?fit=984%2C891&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/image-31.png?fit=984%2C891&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/image-31.png?fit=984%2C891&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/image-31.png?fit=984%2C891&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":87348,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/01\/jogo-entre-comercial-e-noroeste-pela-copa-paulista-tem-nova-data-e-horario\/","url_meta":{"origin":88370,"position":1},"title":"Jogo entre Comercial e Noroeste pela Copa Paulista tem nova data e hor\u00e1rio","author":"noticiasribeiraopreto.com.br","date":"1 de July de 2026","format":false,"excerpt":"A estreia do Comercial na Copa Paulista teve a data e o hor\u00e1rio alterados pela Federa\u00e7\u00e3o Paulista de Futebol (FPF). A partida contra o Noroeste, v\u00e1lida pela primeira rodada da competi\u00e7\u00e3o, ser\u00e1 disputada no dia 18 de julho, um s\u00e1bado, \u00e0s 16h, no est\u00e1dio Palma Travassos, em Ribeir\u00e3o Preto. Inicialmente,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":88392,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/18\/comercial-estreia-na-copa-paulista-com-vitoria-sobre-noroeste\/","url_meta":{"origin":88370,"position":2},"title":"Comercial estreia na Copa Paulista com vit\u00f3ria sobre Noroeste","author":"noticiasribeiraopreto.com.br","date":"18 de July de 2026","format":false,"excerpt":"O Norusca teve a primeira boa oportunidade do jogo, aos 18 minutos do primeiro tempo, mas a defesa comercialina impediu o gol. A etapa inicial foi marcada por pouca criatividade e uma batalha f\u00edsica dos dois lados. Aos 40, Gustavo Henrique parou no goleiro rival na melhor chance alvinegra antes\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/ATA-Paulo-Victor-Raul-Ramos-3-scaled.jpeg?fit=1170%2C780&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/ATA-Paulo-Victor-Raul-Ramos-3-scaled.jpeg?fit=1170%2C780&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/ATA-Paulo-Victor-Raul-Ramos-3-scaled.jpeg?fit=1170%2C780&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/ATA-Paulo-Victor-Raul-Ramos-3-scaled.jpeg?fit=1170%2C780&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/ATA-Paulo-Victor-Raul-Ramos-3-scaled.jpeg?fit=1170%2C780&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":88681,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/23\/copa-paulista-partida-entre-comercial-e-uniao-sao-joao-tem-data-alterada\/","url_meta":{"origin":88370,"position":3},"title":"Copa Paulista: partida entre Comercial e Uni\u00e3o S\u00e3o Jo\u00e3o tem data alterada","author":"noticiasribeiraopreto.com.br","date":"23 de July de 2026","format":false,"excerpt":"A Federa\u00e7\u00e3o Paulista de Futebol (FPF) alterou a data da partida entre Comercial e Uni\u00e3o S\u00e3o Jo\u00e3o, v\u00e1lida pela terceira rodada do Grupo 2 da Copa Paulista. A entidade comunicou a mudan\u00e7a nesta quarta-feira (22). Inicialmente, o confronto aconteceria no domingo, 2 de agosto. Com a altera\u00e7\u00e3o, o jogo ser\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/1784845617_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-61.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/1784845617_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-61.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/1784845617_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-61.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/1784845617_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-61.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/1784845617_Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-61.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":90448,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/08\/22\/comercial-perde-para-noroeste-e-disputara-play-in-da-copa-paulista\/","url_meta":{"origin":88370,"position":4},"title":"Comercial perde para Noroeste e disputar\u00e1 \u2018play-in\u2019 da Copa Paulista","author":"noticiasribeiraopreto.com.br","date":"22 de August de 2026","format":false,"excerpt":"\r \r \r Em jogo repleto de gols, Bafo deixa lideran\u00e7a escapar e ter\u00e1 EC S\u00e3o Bernardo pela frente\r \r 22 de agosto de 2026 17:34 \r Compartilhar1 \r *_Por Hugo Luque_*O Comercial foi derrotado por 4 a 3 pelo Noroeste neste s\u00e1bado (22), no Alfredo de Castilho, pela sexta\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/IMG_7353.jpeg?fit=1000%2C653&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/IMG_7353.jpeg?fit=1000%2C653&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/IMG_7353.jpeg?fit=1000%2C653&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/IMG_7353.jpeg?fit=1000%2C653&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":71746,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/06\/09\/jornal-da-franca-francana-aperta-o-ritmo-de-preparacao-pra-estreia-na-copa-paulista-contra-comercial\/","url_meta":{"origin":88370,"position":5},"title":"Jornal da Franca &#8211; Francana aperta o ritmo de prepara\u00e7\u00e3o pra estreia na Copa Paulista contra Comercial\u00a0","author":"noticiasribeiraopreto.com.br","date":"9 de June de 2025","format":false,"excerpt":"compartilhar no whatsapp compartilhar no telegram compartilhar no facebook compartilhar no linkedin Time est\u00e1 na reta decisiva de prepara\u00e7\u00e3o para encarar o Bafo pela Copinha A Associa\u00e7\u00e3o Atl\u00e9tica Francana est\u00e1 em reta final de prepara\u00e7\u00e3o para a estreia na Copa Paulista, que acontecer\u00e1 no dia 14 contra o Comercial. O\u2026","rel":"","context":"In &quot;Not\u00edcias de Franca-SP&quot;","block_context":{"text":"Not\u00edcias de Franca-SP","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/noticias-franca-sp\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/1749508389_IMG_20250607_002948.jpg?fit=1080%2C774&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/1749508389_IMG_20250607_002948.jpg?fit=1080%2C774&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/1749508389_IMG_20250607_002948.jpg?fit=1080%2C774&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/1749508389_IMG_20250607_002948.jpg?fit=1080%2C774&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/1749508389_IMG_20250607_002948.jpg?fit=1080%2C774&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peQAOb-mZk","jetpack_featured_media_url":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/2-Treino-Maison_Sales-Up-scaled.jpg?fit=624%2C780&ssl=1","_links":{"self":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/88370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=88370"}],"version-history":[{"count":0,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/88370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/media\/88371"}],"wp:attachment":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=88370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=88370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=88370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}