{"id":88392,"date":"2026-07-18T18:37:09","date_gmt":"2026-07-18T21:37:09","guid":{"rendered":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/18\/comercial-estreia-na-copa-paulista-com-vitoria-sobre-noroeste\/"},"modified":"2026-07-18T18:37:09","modified_gmt":"2026-07-18T21:37:09","slug":"comercial-estreia-na-copa-paulista-com-vitoria-sobre-noroeste","status":"publish","type":"post","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/18\/comercial-estreia-na-copa-paulista-com-vitoria-sobre-noroeste\/","title":{"rendered":"Comercial estreia na Copa Paulista com vit\u00f3ria sobre Noroeste"},"content":{"rendered":"<div class='code-block code-block-1' style='margin: 8px 0 8px auto; text-align: right; display: block; clear: both;'>\n<p><a href=\"https:\/\/wa.link\/vpicfd\"><img data-recalc-dims=\"1\" class=\"wp-image-4922\" style=\"aspect-ratio: 2.0253164556962027; width: 561px; height: auto;\" src=\"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/grupo-de-empregos-whatsapp-e-facebook-ismael-colosi-vagas.jpg?ssl=1\" alt=\"\" \/><\/a><\/p>\n<!-- \/wp:image -->\n<\/div>\n<p> <br \/>\n<\/p>\n<div data-block-type=\"unstyled\" data-block-weight=\"24\" data-block-id=\"8\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Artigo - Link no Texto\">O Norusca teve a primeira boa oportunidade do jogo, aos 18 minutos do primeiro tempo, mas a defesa comercialina impediu o gol. A etapa inicial foi marcada por pouca criatividade e uma batalha f\u00edsica dos dois lados. Aos 40, Gustavo Henrique parou no goleiro rival na melhor chance alvinegra antes do intervalo.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Artigo - Link no Texto\">O jogo foi \u201cdesbloqueado\u201d na volta do vesti\u00e1rio. Logo aos dois minutos, Filipinho deu belo passe e, ap\u00f3s sa\u00edda ruim do arqueiro, Paulo Victor abriu o placar.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Artigo - Link no Texto\">Remanescente da S\u00e9rie A4 do Campeonato Paulista, o atacante viveu seus melhores dez minutos com a camisa do Le\u00e3o do Norte no in\u00edcio da segunda metade. Aos 12, ele encobriu o goleiro, de cabe\u00e7a, ampliou para o Comercial e deu n\u00fameros finais ao duelo, que ainda viu o Noroeste tentar reduzir a desvantagem no final, sem sucesso.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Artigo - Link no Texto\">Com o triunfo, o Bafo foi \u00e0 lideran\u00e7a do Grupo 2 com tr\u00eas pontos. XV de Piracicaba e Uni\u00e3o S\u00e3o Jo\u00e3o ainda se enfrentam durante a semana. O pr\u00f3ximo advers\u00e1rio do conjunto ribeir\u00e3o-pretano \u00e9 o XV, \u00e0s 18h do pr\u00f3ximo s\u00e1bado, no Bar\u00e3o da Serra Negra.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/comercial-estreia-na-copa-paulista-com-vitoria-sobre-noroeste\/\">Texto original daqui <\/a><\/p>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>O Norusca teve a primeira boa oportunidade do jogo, aos 18 minutos do primeiro tempo, mas a defesa comercialina impediu o gol. A etapa inicial&#8230;<\/p>\n","protected":false},"author":1,"featured_media":88393,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[705,707,1785,3992,762,468,1672],"class_list":["post-88392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-comercial","tag-copa","tag-estreia","tag-noroeste","tag-paulista","tag-sobre","tag-vitoria"],"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":88394,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/18\/comercial-vence-o-noroeste-e-estreia-com-vitoria-na-copa-paulista-2026\/","url_meta":{"origin":88392,"position":0},"title":"Comercial vence o Noroeste e estreia com vit\u00f3ria na Copa Paulista 2026","author":"noticiasribeiraopreto.com.br","date":"18 de July de 2026","format":false,"excerpt":"O Comercial venceu o Noroeste por 2 a 0 na tarde deste s\u00e1bado (18), no est\u00e1dio Palma Travassos, em Ribeir\u00e3o Preto, pela primeira rodada da Copa Paulista 2026. Os dois gols da equipe de Ribeir\u00e3o Preto sa\u00edram no segundo tempo. O atacante Paulo Vitor, camisa 9 do Bafo, balan\u00e7ou as\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/image-31.png?fit=984%2C891&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/image-31.png?fit=984%2C891&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/image-31.png?fit=984%2C891&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/image-31.png?fit=984%2C891&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":88370,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/18\/comercial-estreia-na-copa-paulista-contra-noroeste\/","url_meta":{"origin":88392,"position":1},"title":"Comercial estreia na Copa Paulista contra Noroeste","author":"noticiasribeiraopreto.com.br","date":"18 de July de 2026","format":false,"excerpt":"Por Hugo Luque O Comercial estreia na Copa Paulista neste s\u00e1bado (18), \u00e0s 16h, no Est\u00e1dio Palma Travassos, contra o Noroeste. No primeiro duelo do Grupo 2, o Le\u00e3o do Norte quer come\u00e7ar sua jornada no torneio com o \u201cp\u00e9 direito\u201d para que o novo elenco ganhe confian\u00e7a na briga\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/2-Treino-Maison_Sales-Up-scaled.jpg?fit=624%2C780&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/2-Treino-Maison_Sales-Up-scaled.jpg?fit=624%2C780&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/2-Treino-Maison_Sales-Up-scaled.jpg?fit=624%2C780&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":72224,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/06\/14\/comercial-estreia-com-vitoria-na-copa-paulista\/","url_meta":{"origin":88392,"position":2},"title":"Comercial estreia com vit\u00f3ria na Copa Paulista","author":"noticiasribeiraopreto.com.br","date":"14 de June de 2025","format":false,"excerpt":"Bafo leva a melhor sobre Francana com gol \u00fanico 14 de junho de 2025 17:340 Compartilhar0 Por Hugo Luque O Comercial derrotou a Francana por 1 a 0 neste s\u00e1bado (14), na estreia da Copa Paulista. O gol foi marcado pelo tamb\u00e9m estreante Carlos Baj\u00e9. No Palma Travassos, o Le\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/IMG_2852-scaled.jpeg?fit=750%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/IMG_2852-scaled.jpeg?fit=750%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/IMG_2852-scaled.jpeg?fit=750%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/IMG_2852-scaled.jpeg?fit=750%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":90446,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/08\/22\/ja-classificado-comercial-perde-para-o-noroeste-na-copa-paulista\/","url_meta":{"origin":88392,"position":3},"title":"J\u00e1 classificado, Comercial perde para o Noroeste na Copa Paulista","author":"noticiasribeiraopreto.com.br","date":"22 de August de 2026","format":false,"excerpt":"J\u00e1 classificado, o Comercial foi derrotado por 4 a 3 pelo Noroeste, na tarde deste s\u00e1bado (22), pela Copa Paulista. O confronto, que encerrou a primeira fase no Grupo B, foi realizado no est\u00e1dio Alfredo Castilho, em Bauru. Receba not\u00edcias do\u00a0acidade on Ribeir\u00e3o\u00a0no WhatsApp e fique por dentro de tudo!\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/noroeste-comercial-copa-paulista-1.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/noroeste-comercial-copa-paulista-1.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/noroeste-comercial-copa-paulista-1.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/noroeste-comercial-copa-paulista-1.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/08\/noroeste-comercial-copa-paulista-1.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":72232,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2025\/06\/14\/comercial-estreia-com-vitoria-sobre-a-francana-na-copa-paulista\/","url_meta":{"origin":88392,"position":4},"title":"Comercial estreia com vit\u00f3ria sobre a Francana na Copa Paulista","author":"noticiasribeiraopreto.com.br","date":"14 de June de 2025","format":false,"excerpt":"O Comercial venceu a Francana por 1 a 0 neste s\u00e1bado (14), no Est\u00e1dio Palma Travassos, em Ribeir\u00e3o Preto, na estreia pelo Grupo B, na primeira rodada da Copa Paulista. O \u00fanico gol da partida foi anotado por Carlos Baj\u00e9, aos 38 minutos do primeiro tempo, ap\u00f3s aproveitar a sobra\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/2RAU0483_2025-06-14_20-13-20.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/2RAU0483_2025-06-14_20-13-20.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/2RAU0483_2025-06-14_20-13-20.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/2RAU0483_2025-06-14_20-13-20.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2025\/06\/2RAU0483_2025-06-14_20-13-20.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":87348,"url":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/2026\/07\/01\/jogo-entre-comercial-e-noroeste-pela-copa-paulista-tem-nova-data-e-horario\/","url_meta":{"origin":88392,"position":5},"title":"Jogo entre Comercial e Noroeste pela Copa Paulista tem nova data e hor\u00e1rio","author":"noticiasribeiraopreto.com.br","date":"1 de July de 2026","format":false,"excerpt":"A estreia do Comercial na Copa Paulista teve a data e o hor\u00e1rio alterados pela Federa\u00e7\u00e3o Paulista de Futebol (FPF). A partida contra o Noroeste, v\u00e1lida pela primeira rodada da competi\u00e7\u00e3o, ser\u00e1 disputada no dia 18 de julho, um s\u00e1bado, \u00e0s 16h, no est\u00e1dio Palma Travassos, em Ribeir\u00e3o Preto. Inicialmente,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2024\/12\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-12-23T124251.755_2024-12-23_15-42-58_png_2024-12-23_15-42-58.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/peQAOb-mZG","jetpack_featured_media_url":"https:\/\/i0.wp.com\/noticiasribeiraopreto.com.br\/wp-content\/uploads\/2026\/07\/ATA-Paulo-Victor-Raul-Ramos-3-scaled.jpeg?fit=1170%2C780&ssl=1","_links":{"self":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/88392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=88392"}],"version-history":[{"count":0,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/posts\/88392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/media\/88393"}],"wp:attachment":[{"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=88392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=88392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasribeiraopreto.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=88392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}